{"id":4712,"count":1,"description":"","link":"https:\/\/hmd.site\/av\/category\/%e5%96%89%e5%a7%a6%e3%82%a4%e3%83%a9%e3%83%9e%e3%83%81%e3%82%aa%e8%aa%bf%e6%95%99\/","name":"\u5589\u59e6\u30a4\u30e9\u30de\u30c1\u30aa\u8abf\u6559","slug":"%e5%96%89%e5%a7%a6%e3%82%a4%e3%83%a9%e3%83%9e%e3%83%81%e3%82%aa%e8%aa%bf%e6%95%99","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/hmd.site\/av\/wp-json\/wp\/v2\/categories\/4712","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hmd.site\/av\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/hmd.site\/av\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/hmd.site\/av\/wp-json\/wp\/v2\/posts?categories=4712"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}