{"id":1049,"count":6,"description":"","link":"https:\/\/hmd.site\/av\/tag\/%e4%ba%94%e5%8d%81%e5%b5%90%e3%81%97%e3%81%ae%e3%81%b6\/","name":"\u4e94\u5341\u5d50\u3057\u306e\u3076","slug":"%e4%ba%94%e5%8d%81%e5%b5%90%e3%81%97%e3%81%ae%e3%81%b6","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/hmd.site\/av\/wp-json\/wp\/v2\/tags\/1049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hmd.site\/av\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/hmd.site\/av\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/hmd.site\/av\/wp-json\/wp\/v2\/posts?tags=1049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}