{"id":1297,"count":13,"description":"","link":"https:\/\/hmd.site\/av\/tag\/%e3%83%a9%e3%83%96%e3%83%9b%e3%83%86%e3%83%ab\/","name":"\u30e9\u30d6\u30db\u30c6\u30eb","slug":"%e3%83%a9%e3%83%96%e3%83%9b%e3%83%86%e3%83%ab","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/hmd.site\/av\/wp-json\/wp\/v2\/tags\/1297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hmd.site\/av\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/hmd.site\/av\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/hmd.site\/av\/wp-json\/wp\/v2\/posts?tags=1297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}